{"id":303,"date":"2024-12-09T09:54:08","date_gmt":"2024-12-09T09:54:08","guid":{"rendered":"https:\/\/oviedo.cnt.es\/?p=303"},"modified":"2024-12-09T10:04:00","modified_gmt":"2024-12-09T10:04:00","slug":"ante-la-escalada-belica-en-ucrania-declaracion","status":"publish","type":"post","link":"https:\/\/oviedo.cnt.es\/index.php\/2024\/12\/09\/ante-la-escalada-belica-en-ucrania-declaracion\/","title":{"rendered":"ANTE LA ESCALADA B\u00c9LICA EN UCRANIA &#8211; DECLARACI\u00d3N"},"content":{"rendered":"<h2>COMUNICADO DE LA REGIONAL ASTURIAS-LE\u00d3N DE LA CNT<\/h2>\n<p class=\"has-medium-font-size\">Una vez m\u00e1s los dirigentes pol\u00edticos, lejos de abogar por el bienestar social de la ciudadan\u00eda, priorizan la econom\u00eda de guerra y los intereses de la industria armament\u00edstica. La alarmante escalada b\u00e9lica en Ucrania, sumada a los posicionamientos geopol\u00edticos en el conflicto b\u00e9lico, hacen presagiar un avance del conflicto a escala mundial. Ante este lamentable panorama,\u00a0desde la CNT Asturias-Le\u00f3n\u00a0manifestamos nuestra <strong>condena a esta guerra de intereses<\/strong> que se est\u00e1 perpetrando y <strong>rechazamos la posici\u00f3n del Estado espa\u00f1ol ante el conflicto<\/strong> que lejos de ejercer una posici\u00f3n no beligerante respalda esta guerra incrementando el gasto militar.<\/p>\n<p class=\"has-medium-font-size\">Desde el inicio del conflicto hemos sido testigos, una vez m\u00e1s, de la inoperancia de los dirigentes pol\u00edticos. Desde Europa se cre\u00f3 el Fondo Europeo de \u00abApoyo a la Paz\u00bb. Pero <strong>\u00bfpor qu\u00e9 lo llaman paz cuando quieren decir guerra?<\/strong> Las fuentes oficiales hablan de 6.100 millones de euros que no han ido a parar a las personas m\u00e1s damnificadas por la guerra, sino a reforzar la militarizaci\u00f3n del conflicto. En la misma l\u00ednea, el Ministerio de Asuntos Exteriores del Estado espa\u00f1ol emit\u00eda un comunicado conjunto con varios pa\u00edses europeos en el que consideran imperativo fortalecer la OTAN e incrementar el gasto militar, manifestando que es posible que el aumento supere el 2% del PIB.<\/p>\n<p class=\"has-medium-font-size\">Cada euro que se destina a la guerra es un euro que se resta de las inversiones en los servicios p\u00fablicos. La paz no se logra con m\u00e1s armas y estas medidas no hacen m\u00e1s que socavar el bienestar de las personas y los derechos sociales.<\/p>\n<p class=\"has-medium-font-size\">En relaci\u00f3n con la problem\u00e1tica expuesta\u00a0<strong>hacemos un llamamiento de movilizaci\u00f3n a la clase trabajadora<\/strong>, es el\u00a0<em>momento de alzar la voz ante los tambores de guerra y defender la justicia social, la igualdad y la paz.<\/em><\/p>\n<p>___<\/p>\n<h2>COMUNIC\u00c1U DE LA REXONAL ASTURIES-LLI\u00d3N DE LA CNT<\/h2>\n<p class=\"has-medium-font-size\">Una vegada m\u00e1s los dirixentes pol\u00edticos, llue\u00f1e d&#8217;abogar pol bienestar social de la ciudadan\u00eda, prioricen la econom\u00eda de guerra y los intereses de la industria armament\u00edstica. L&#8217;alarmante esguilada b\u00e9lica n&#8217;Ucrania, sumada a los allugamientos geopol\u00edticos nel conflictu b\u00e9licu, faen abarruntar una meyora del conflictu a escala mundial. \u00c9nte esti llamentable panorama, dende la CNT Asturies-Lli\u00f3n manifestamos la nuesa <strong>condena a esta guerra d&#8217;intereses<\/strong> que se ta perpetando y <strong>refugamos la posici\u00f3n del Est\u00e1u espa\u00f1ol \u00e9nte&#8217;l conflictu<\/strong> que llue\u00f1e d&#8217;exercer una posici\u00f3n non batallosa sofita esta guerra amontando&#8217;l gastu militar.<\/p>\n<p class=\"has-medium-font-size\">Dende l&#8217;entamu del conflictu fuimos testigos, una vegada m\u00e1s, de la inoperancia de los dirixentes pol\u00edticos. Dende Europa cre\u00f3se&#8217;l Fondu Europ\u00e9u de \u00abSofitu a la Paz\u00bb. Pero <strong>\u00bfpor qu\u00e9 lo llamen paz cuando quieren dicir guerra?<\/strong> Les fontes oficiales falen de 6.100 millones d&#8217;euros que nun fueron parar a les persones m\u00e1s damnificadas pola guerra, sin\u00f3n a reforzar la militarizaci\u00f3n del conflictu. Na mesma ll\u00ednea, el Ministeriu d&#8217;Asuntos Esteriores del Est\u00e1u espa\u00f1ol emit\u00eda un comunic\u00e1u conxuntu con dellos pa\u00edses europeos nel que consideren imperativu fortalecer la OTAN y amontar el gastu militar, manifestando que ye posible que l&#8217;aumentu supere&#8217;l 2% del PIB.<\/p>\n<p class=\"has-medium-font-size\">Cada euru que se destina a la guerra ye un euru que se resta de les inversiones nos servicios p\u00fablicos. La paz nun se llogra con m\u00e1s armes y estes mid\u00edes nun faen m\u00e1s que socavar el bienestar de les persones y los derechos sociales.<\/p>\n<p class=\"has-medium-font-size\">En relaci\u00f3n cola problem\u00e1tica espuesta <strong>faemos un llamamientu de movilizaci\u00f3n a la clase trabayadora<\/strong>, ye&#8217;l momentu d&#8217;alzar la voz \u00e9nte los tambores de guerra y defender la xusticia social, la iguald\u00e1 y la paz.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"LldMCqV0k6\"><p><a href=\"https:\/\/leon.cnt.es\/2024\/12\/06\/ante-la-escalada-belica-en-ucrania\/\">ANTE LA ESCALADA B\u00c9LICA EN UCRANIA<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abANTE LA ESCALADA B\u00c9LICA EN UCRANIA\u00bb \u2014 Confederaci\u00f3n Nacional del Trabajo - Le\u00f3n\" src=\"https:\/\/leon.cnt.es\/2024\/12\/06\/ante-la-escalada-belica-en-ucrania\/embed\/#?secret=tU2fIzziT4#?secret=LldMCqV0k6\" data-secret=\"LldMCqV0k6\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>COMUNICADO DE LA REGIONAL ASTURIAS-LE\u00d3N DE LA CNT Una vez m\u00e1s los dirigentes pol\u00edticos, lejos de abogar por el bienestar social de la ciudadan\u00eda, priorizan <a class=\"mh-excerpt-more\" href=\"https:\/\/oviedo.cnt.es\/index.php\/2024\/12\/09\/ante-la-escalada-belica-en-ucrania-declaracion\/\" title=\"ANTE LA ESCALADA B\u00c9LICA EN UCRANIA &#8211; DECLARACI\u00d3N\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[81,78,80,79],"class_list":["post-303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicado","tag-antimilitarismo","tag-escalada","tag-paz","tag-ucrania"],"_links":{"self":[{"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/posts\/303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/comments?post=303"}],"version-history":[{"count":5,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/posts\/303\/revisions"}],"predecessor-version":[{"id":309,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/posts\/303\/revisions\/309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/media?parent=303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/categories?post=303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oviedo.cnt.es\/index.php\/wp-json\/wp\/v2\/tags?post=303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}